{"id":20879,"date":"2025-11-23T14:52:40","date_gmt":"2025-11-23T14:52:40","guid":{"rendered":"https:\/\/blog.mergerscorp.com\/guia-completo-para-o-lancamento-de-um-spac-na-nasdaq-da-formacao-ao-encerramento-do-spac\/"},"modified":"2026-05-02T17:25:35","modified_gmt":"2026-05-02T17:25:35","slug":"guia-completo-para-o-lancamento-de-um-spac-na-nasdaq-da-formacao-ao-encerramento-do-spac","status":"publish","type":"post","link":"https:\/\/blog.mergerscorp.com\/pt-br\/guia-completo-para-o-lancamento-de-um-spac-na-nasdaq-da-formacao-ao-encerramento-do-spac\/","title":{"rendered":"Guia completo para o lan\u00e7amento de um SPAC na NASDAQ: da forma\u00e7\u00e3o ao encerramento do SPAC"},"content":{"rendered":"<p data-pm-slice=\"1 1 []\">O lan\u00e7amento de uma Special Purpose Acquisition Company (SPAC) na Nasdaq Stock Market \u00e9 um processo de v\u00e1rias etapas que oferece um caminho mais r\u00e1pido para os mercados p\u00fablicos em compara\u00e7\u00e3o com uma Oferta P\u00fablica Inicial (IPO) tradicional. Uma SPAC \u00e9 essencialmente uma empresa de fachada com &#8220;cheque em branco&#8221; criada exclusivamente para levantar capital por meio de uma IPO com o objetivo de adquirir ou se fundir com uma empresa privada existente, um processo conhecido como &#8220;de-SPAC&#8221;. <\/p>\n<p>Este guia descreve as etapas cr\u00edticas, desde a forma\u00e7\u00e3o inicial e a IPO at\u00e9 a combina\u00e7\u00e3o final de neg\u00f3cios na Nasdaq.<\/p>\n<h2>Fase 1: Forma\u00e7\u00e3o e estrutura\u00e7\u00e3o (o est\u00e1gio do projeto)<\/h2>\n<p>Esse est\u00e1gio inicial estabelece a base para todo o ciclo de vida do SPAC. A qualidade e a reputa\u00e7\u00e3o dos patrocinadores s\u00e3o fundamentais, pois o SPAC n\u00e3o tem hist\u00f3rico operacional nem ativos al\u00e9m do capital inicial. <\/p>\n<h3>1. Re\u00fana a equipe patrocinadora e a tese<\/h3>\n<p>Os patrocinadores s\u00e3o os investidores experientes ou especialistas do setor que formam a equipe de administra\u00e7\u00e3o do SPAC e fornecem o capital inicial.<\/p>\n<ul>\n<li><strong>Perfil do patrocinador:<\/strong> A equipe deve ter um hist\u00f3rico comprovado em investimentos, M&amp;A (fus\u00f5es e aquisi\u00e7\u00f5es) e mercados p\u00fablicos. Os investidores est\u00e3o apostando principalmente na capacidade dos patrocinadores de encontrar e executar uma aquisi\u00e7\u00e3o bem-sucedida. <\/li>\n<li><strong>A tese de investimento:<\/strong> Defina o foco do SPAC. Isso inclui o setor-alvo (por exemplo, tecnologia, energia limpa, sa\u00fade) e a \u00e1rea geogr\u00e1fica. Essa tese deve ser detalhada nos registros p\u00fablicos para atrair os investidores certos.  <\/li>\n<li><strong>A\u00e7\u00f5es dos fundadores (a &#8220;promo\u00e7\u00e3o&#8221;):<\/strong> Os patrocinadores normalmente recebem 20% das a\u00e7\u00f5es ordin\u00e1rias da SPAC por um pre\u00e7o nominal, conhecido como &#8220;Promote&#8221;. Isso incentiva os patrocinadores a maximizar o valor. <\/li>\n<\/ul>\n<h3>2. Forma\u00e7\u00e3o jur\u00eddica e compromisso de capital<\/h3>\n<ul>\n<li><strong>Incorpora\u00e7\u00e3o:<\/strong> O SPAC \u00e9 incorporado, normalmente como uma corpora\u00e7\u00e3o de Delaware ou uma entidade offshore.<\/li>\n<li><strong>Financiamento inicial:<\/strong> Os patrocinadores contribuem com o capital necess\u00e1rio para cobrir os custos de forma\u00e7\u00e3o e o roadshow da IPO (estimado em cerca de US$ 800.000 a US$ 1 milh\u00e3o). Esse capital \u00e9 geralmente chamado de capital &#8220;de risco&#8221; e \u00e9 usado para comprar b\u00f4nus de subscri\u00e7\u00e3o em uma coloca\u00e7\u00e3o privada simult\u00e2nea \u00e0 IPO. <\/li>\n<li><strong>Subscritores e consultores:<\/strong> Contrate bancos de investimento de primeira linha (subscritores) para gerenciar o IPO e equipes jur\u00eddicas e cont\u00e1beis experientes (advogado da SEC e auditores registrados no PCAOB) para navegar no complexo ambiente regulat\u00f3rio.<\/li>\n<\/ul>\n<h3>3. Requisitos de listagem inicial da Nasdaq (est\u00e1gio de IPO)<\/h3>\n<p>Os SPACs devem atender aos requisitos de listagem da NASDAQ no momento da IPO. Esses requisitos s\u00e3o menos rigorosos do que os requisitos para a empresa operacional p\u00f3s-fus\u00e3o, mas s\u00e3o essenciais para a negocia\u00e7\u00e3o. <\/p>\n<table>\n<tbody>\n<tr>\n<th>Exig\u00eancia<\/th>\n<th>Padr\u00e3o NASDAQ<\/th>\n<th>Detalhe<\/th>\n<\/tr>\n<tr>\n<td><strong>Flutua\u00e7\u00e3o p\u00fablica<\/strong><\/td>\n<td>Varia de acordo com o n\u00edvel de mercado<\/td>\n<td>O SPAC deve atender aos requisitos de liquidez do n\u00edvel escolhido (Global Select, Global Market ou Capital Market).<\/td>\n<\/tr>\n<tr>\n<td><strong>Valor m\u00ednimo das a\u00e7\u00f5es detidas publicamente<\/strong><\/td>\n<td>Geralmente, um valor m\u00ednimo (por exemplo, US$ 45 milh\u00f5es para o Mercado Global).<\/td>\n<td>Esse \u00e9 o valor das a\u00e7\u00f5es detidas por n\u00e3o afiliados.<\/td>\n<\/tr>\n<tr>\n<td><strong>Conta fiduci\u00e1ria m\u00ednima<\/strong><\/td>\n<td><strong>Regra 5101-2:<\/strong> Deve depositar pelo menos 90% dos recursos brutos do IPO em uma conta fiduci\u00e1ria segregada.<\/td>\n<td>Isso protege os acionistas p\u00fablicos se nenhuma aquisi\u00e7\u00e3o for conclu\u00edda.<\/td>\n<\/tr>\n<tr>\n<td><strong>Aprova\u00e7\u00e3o dos acionistas<\/strong><\/td>\n<td>A combina\u00e7\u00e3o inicial de neg\u00f3cios deve ser aprovada pela maioria dos acionistas.<\/td>\n<td> <\/td>\n<\/tr>\n<tr>\n<td><strong>Governan\u00e7a corporativa<\/strong><\/td>\n<td>Conformidade com todos os requisitos da Nasdaq Rule 5600 Series (conselho majoritariamente independente, auditoria independente, comit\u00eas de remunera\u00e7\u00e3o e de nomea\u00e7\u00e3o e um C\u00f3digo de Conduta).<\/td>\n<td> <\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h2>Fase 2: a oferta p\u00fablica inicial (IPO)<\/h2>\n<p>Essa fase se concentra na aprova\u00e7\u00e3o regulat\u00f3ria e no levantamento do capital necess\u00e1rio de investidores p\u00fablicos.<\/p>\n<h3>4. Registro e revis\u00e3o da SEC (Formul\u00e1rio S-1)<\/h3>\n<ul>\n<li><strong>Apresenta\u00e7\u00e3o do S-1:<\/strong> O SPAC apresenta uma declara\u00e7\u00e3o de registro inicial (Formul\u00e1rio S-1) \u00e0 Securities and Exchange Commission (SEC). Esse prospecto detalha a equipe de administra\u00e7\u00e3o do SPAC, sua estrat\u00e9gia de aquisi\u00e7\u00e3o, a estrutura da unidade de IPO (a\u00e7\u00f5es mais b\u00f4nus de subscri\u00e7\u00e3o) e os termos da conta fiduci\u00e1ria. <\/li>\n<li><strong>An\u00e1lise da SEC:<\/strong> A equipe da SEC faz coment\u00e1rios sobre a minuta da S-1. O advogado do SPAC aborda esses coment\u00e1rios por meio de v\u00e1rias emendas. O tempo para a efetiva\u00e7\u00e3o \u00e9 normalmente mais curto para um SPAC (8 a 12 semanas) em compara\u00e7\u00e3o com um IPO de empresa operacional tradicional.  <\/li>\n<\/ul>\n<h3>5. Precifica\u00e7\u00e3o e Roadshow<\/h3>\n<ul>\n<li><strong>Estrutura da unidade:<\/strong> As a\u00e7\u00f5es do SPAC s\u00e3o normalmente vendidas como &#8220;unidades&#8221;, geralmente consistindo em uma a\u00e7\u00e3o ordin\u00e1ria e uma fra\u00e7\u00e3o de um b\u00f4nus de subscri\u00e7\u00e3o. Historicamente, o pre\u00e7o unit\u00e1rio \u00e9 de US$ 10,00. <\/li>\n<li><strong>O Roadshow:<\/strong> A equipe de administra\u00e7\u00e3o do SPAC e os subscritores comercializam a oferta para investidores institucionais. Essa apresenta\u00e7\u00e3o de marketing concentra-se inteiramente na reputa\u00e7\u00e3o, no hist\u00f3rico e na experi\u00eancia espec\u00edfica do setor da equipe patrocinadora. <\/li>\n<li><strong>Precifica\u00e7\u00e3o e fechamento:<\/strong> Uma vez garantido o interesse suficiente do investidor, o IPO \u00e9 precificado e fechado. Os recursos brutos s\u00e3o transferidos diretamente para a conta fiduci\u00e1ria. <\/li>\n<\/ul>\n<h3>6. Listagem e negocia\u00e7\u00e3o na NASDAQ<\/h3>\n<ul>\n<li><strong>Listagem:<\/strong> O SPAC est\u00e1 oficialmente listado na Nasdaq com um s\u00edmbolo de registro reservado.<\/li>\n<li><strong>Negocia\u00e7\u00e3o separada:<\/strong> Logo ap\u00f3s a IPO (normalmente de 30 a 52 dias), as unidades s\u00e3o separadas em a\u00e7\u00f5es ordin\u00e1rias e b\u00f4nus de subscri\u00e7\u00e3o negociados individualmente.<\/li>\n<\/ul>\n<h2>Fase 3: A busca do alvo e o De-SPAC (o est\u00e1gio de aquisi\u00e7\u00e3o)<\/h2>\n<p>Com o dinheiro garantido no trust, a SPAC agora tem um prazo limitado &#8211; normalmente de 18 a 24 meses &#8211; para identificar, negociar e concluir uma fus\u00e3o com uma empresa operacional privada.<\/p>\n<h3>7. Identifica\u00e7\u00e3o do alvo e dilig\u00eancia pr\u00e9via<\/h3>\n<ul>\n<li><strong>Triagem e divulga\u00e7\u00e3o:<\/strong> A equipe do patrocinador aproveita sua rede para encontrar uma empresa privada de alto crescimento que esteja pronta para os mercados p\u00fablicos (ou seja, &#8220;pronta para a empresa p\u00fablica&#8221;).<\/li>\n<li><strong>Carta de Inten\u00e7\u00e3o (LOI) e Negocia\u00e7\u00f5es:<\/strong> Uma vez identificada a meta, o SPAC negocia uma LOI n\u00e3o vinculante, seguida de uma extensa due diligence (DD) financeira, jur\u00eddica e operacional.<\/li>\n<li><strong>Prepara\u00e7\u00e3o da empresa p\u00fablica:<\/strong> A empresa-alvo deve preparar rapidamente sua infraestrutura para relat\u00f3rios p\u00fablicos, incluindo finan\u00e7as auditadas pela PCAOB, conformidade com a Sarbanes-Oxley (SOX) e controles internos da empresa p\u00fablica.<\/li>\n<\/ul>\n<h3>8. O Acordo de Fus\u00e3o e o Financiamento PIPE<\/h3>\n<ul>\n<li><strong>Acordo definitivo:<\/strong> O SPAC e a empresa-alvo assinam um acordo definitivo de fus\u00e3o, estabelecendo a avalia\u00e7\u00e3o e a estrutura do neg\u00f3cio.<\/li>\n<li><strong>PIPE (Investimento Privado em A\u00e7\u00f5es P\u00fablicas):<\/strong> Para compensar poss\u00edveis resgates por parte dos acionistas p\u00fablicos do SPAC e para levantar capital de crescimento adicional, uma transa\u00e7\u00e3o PIPE simult\u00e2nea \u00e9 frequentemente executada. Os investidores institucionais comprometem capital para comprar a\u00e7\u00f5es da empresa resultante da fus\u00e3o pelo pre\u00e7o do IPO. Garantir um PIPE forte \u00e9 fundamental, pois reduz a incerteza do dinheiro dispon\u00edvel no fechamento.  <\/li>\n<\/ul>\n<h3>9. Divulga\u00e7\u00e3o da SEC e voto dos acionistas<\/h3>\n<ul>\n<li><strong>Registro S-4\/Proxy:<\/strong> O SPAC apresenta uma declara\u00e7\u00e3o de procura\u00e7\u00e3o (ou uma declara\u00e7\u00e3o de registro S-4 se novos t\u00edtulos estiverem sendo emitidos) \u00e0 SEC. Esse documento, conhecido como &#8220;De-SPAC Filing&#8221;, \u00e9 extenso e cont\u00e9m informa\u00e7\u00f5es detalhadas sobre a empresa-alvo, inclusive seu hist\u00f3rico financeiro, proje\u00e7\u00f5es, discuss\u00e3o da administra\u00e7\u00e3o e os termos da fus\u00e3o. <\/li>\n<li><strong>A op\u00e7\u00e3o de resgate:<\/strong> Os acionistas do SPAC recebem a procura\u00e7\u00e3o e t\u00eam duas op\u00e7\u00f5es:\n<ol>\n<li><strong>Votar a favor da fus\u00e3o<\/strong> e manter suas a\u00e7\u00f5es na nova empresa p\u00fablica resultante da fus\u00e3o.<\/li>\n<li><strong>Resgatar suas a\u00e7\u00f5es<\/strong> por sua parcela proporcional dos recursos da conta fiduci\u00e1ria (normalmente US$ 10,00 por a\u00e7\u00e3o mais juros acumulados).<\/li>\n<\/ol>\n<\/li>\n<li><strong>Reuni\u00e3o de acionistas:<\/strong> \u00c9 realizada uma reuni\u00e3o para aprovar a transa\u00e7\u00e3o. A fus\u00e3o deve ser aprovada pela maioria das a\u00e7\u00f5es em circula\u00e7\u00e3o. <\/li>\n<\/ul>\n<h3>10. Conclus\u00e3o da combina\u00e7\u00e3o de neg\u00f3cios (De-SPAC)<\/h3>\n<ul>\n<li><strong>Fechamento:<\/strong> Se a fus\u00e3o for aprovada e todas as condi\u00e7\u00f5es de fechamento forem atendidas, a transa\u00e7\u00e3o de-SPAC \u00e9 fechada. A empresa-alvo privada \u00e9 legalmente incorporada ao SPAC p\u00fablico. <\/li>\n<li><strong>Mudan\u00e7a de ticker:<\/strong> A entidade combinada muda de nome e come\u00e7a a ser negociada na Nasdaq com um novo s\u00edmbolo de registro, marcando sua estreia como uma empresa p\u00fablica totalmente operacional.<\/li>\n<li><strong>Apresenta\u00e7\u00e3o do Super 8-K:<\/strong> No prazo de quatro dias \u00fateis ap\u00f3s o fechamento, a nova empresa p\u00fablica deve apresentar um Formul\u00e1rio 8-K (&#8220;Super 8-K&#8221;) \u00e0 SEC, contendo todas as informa\u00e7\u00f5es que seriam exigidas em uma declara\u00e7\u00e3o de registro do Formul\u00e1rio 10 para uma nova listagem p\u00fablica.<\/li>\n<\/ul>\n<h2>Fase 4: Conformidade e governan\u00e7a p\u00f3s-fus\u00e3o<\/h2>\n<p>A nova empresa de capital aberto deve agora aderir \u00e0s obriga\u00e7\u00f5es cont\u00ednuas de uma entidade listada na Nasdaq.<\/p>\n<h3>11. Conformidade cont\u00ednua com a Nasdaq<\/h3>\n<ul>\n<li><strong>Listagem cont\u00ednua:<\/strong> A empresa combinada deve atender aos requisitos de listagem <em>inicial<\/em> da Nasdaq no momento do de-SPAC. Isso inclui atender a padr\u00f5es mais elevados de valor de mercado de a\u00e7\u00f5es detidas publicamente, patrim\u00f4nio l\u00edquido e m\u00e9tricas de desempenho financeiro. <\/li>\n<li><strong>Governan\u00e7a corporativa:<\/strong> A empresa deve manter os padr\u00f5es de governan\u00e7a corporativa da Nasdaq, inclusive ter um conselho de administra\u00e7\u00e3o majoritariamente independente e comit\u00eas totalmente independentes (Auditoria, Remunera\u00e7\u00e3o, Indica\u00e7\u00f5es).<\/li>\n<li><strong>Relat\u00f3rios p\u00fablicos:<\/strong> A empresa est\u00e1 sujeita a todas as obriga\u00e7\u00f5es de relat\u00f3rios da SEC (registros 10-K, 10-Q, 8-K) e deve manter controles e procedimentos eficazes de divulga\u00e7\u00e3o.<\/li>\n<\/ul>\n<h3>12. Principais riscos e considera\u00e7\u00f5es<\/h3>\n<ul>\n<li><strong>Risco de resgate:<\/strong> altos resgates de acionistas podem reduzir significativamente o caixa dispon\u00edvel para a empresa resultante da fus\u00e3o, for\u00e7ando-a a depender fortemente do PIPE ou exigindo que o patrocinador obtenha financiamento adicional.<\/li>\n<li><strong>Exame minucioso da avalia\u00e7\u00e3o:<\/strong> A SEC e os investidores p\u00fablicos d\u00e3o grande \u00eanfase \u00e0 avalia\u00e7\u00e3o da empresa-alvo e \u00e0s proje\u00e7\u00f5es financeiras divulgadas na declara\u00e7\u00e3o de procura\u00e7\u00e3o. As proje\u00e7\u00f5es devem ser bem fundamentadas e defens\u00e1veis. <\/li>\n<li><strong>Dilui\u00e7\u00e3o e bloqueio do patrocinador:<\/strong> Normalmente, os patrocinadores enfrentam um per\u00edodo de bloqueio de um ano para suas a\u00e7\u00f5es fundadoras. A alta propor\u00e7\u00e3o do patrim\u00f4nio do patrocinador (o Promote) tamb\u00e9m leva a uma dilui\u00e7\u00e3o significativa para os outros acionistas. <\/li>\n<li><strong>O rel\u00f3gio de tempo:<\/strong> Se o SPAC n\u00e3o conseguir consumar uma combina\u00e7\u00e3o de neg\u00f3cios dentro do prazo especificado (geralmente de 18 a 24 meses), ele dever\u00e1 se dissolver e devolver os fundos da conta fiduci\u00e1ria (mais juros) aos acionistas p\u00fablicos. Os patrocinadores perdem seu capital de promo\u00e7\u00e3o e de risco. <\/li>\n<\/ul>\n<h2>Resumo da linha do tempo<\/h2>\n<p>A fase de IPO de um SPAC \u00e9 relativamente r\u00e1pida, enquanto o processo de M&amp;A que se segue pode ser complexo e desafiador.<\/p>\n<table>\n<tbody>\n<tr>\n<th>Fase<\/th>\n<th>Cronograma estimado<\/th>\n<th>Principais resultados<\/th>\n<\/tr>\n<tr>\n<td><strong>I. Forma\u00e7\u00e3o<\/strong><\/td>\n<td>4 a 8 semanas<\/td>\n<td>Equipe do patrocinador formada, capital inicial comprometido, subscritores contratados, advogado contratado.<\/td>\n<\/tr>\n<tr>\n<td><strong>II. IPO DO SPAC <\/strong><\/td>\n<td>8-12 semanas<\/td>\n<td>Efetiva\u00e7\u00e3o do registro S-1, Roadshow, precifica\u00e7\u00e3o da IPO, recursos depositados em fideicomisso, listagem na Nasdaq.<\/td>\n<\/tr>\n<tr>\n<td><strong>III. Pesquisa de alvos <\/strong><\/td>\n<td>6-18 meses<\/td>\n<td>Alvo identificado, due diligence conduzida, acordo de fus\u00e3o assinado.<\/td>\n<\/tr>\n<tr>\n<td><strong>IV. De-SPAC <\/strong><\/td>\n<td>3-5 meses<\/td>\n<td>Arquivamento de S-4\/Proxy, an\u00e1lise\/coment\u00e1rios da SEC, fechamento de financiamento PIPE, vota\u00e7\u00e3o de acionistas, mudan\u00e7a de ticker.<\/td>\n<\/tr>\n<tr>\n<td><strong>V. Empresa p\u00fablica<\/strong><\/td>\n<td>Em andamento<\/td>\n<td>Conformidade com a SEC\/Nasdaq, relat\u00f3rios financeiros, rela\u00e7\u00f5es com investidores.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Este guia oferece uma vis\u00e3o geral estrutural das complexidades envolvidas na introdu\u00e7\u00e3o de um SPAC na Nasdaq. O lan\u00e7amento de um SPAC exige um planejamento meticuloso, uma s\u00f3lida reputa\u00e7\u00e3o do patrocinador e recursos jur\u00eddicos e financeiros significativos para superar os obst\u00e1culos regulat\u00f3rios e de mercado. <\/p>\n<h2 data-pm-slice=\"1 1 []\">Parceria com a Mergerscorp SPAC TEAM<\/h2>\n<p>Para navegar pelas complexidades de uma IPO de SPAC e da transa\u00e7\u00e3o subsequente de desespaciliza\u00e7\u00e3o, \u00e9 necess\u00e1rio mais do que capital; \u00e9 preciso uma execu\u00e7\u00e3o impec\u00e1vel, conhecimento regulat\u00f3rio e uma rede de consultores confi\u00e1veis.<\/p>\n<p>Se voc\u00ea \u00e9 um patrocinador institucional que busca maximizar a promo\u00e7\u00e3o ou uma empresa privada de alto crescimento que est\u00e1 considerando entrar no mercado p\u00fablico por meio de uma aquisi\u00e7\u00e3o, o momento de criar sua estrat\u00e9gia \u00e9 agora.<\/p>\n<p><strong>Conecte-se com a EQUIPE SPAC da Mergerscorp hoje mesmo para:<\/strong><\/p>\n<ul>\n<li><strong>Refine sua tese:<\/strong> Desenvolva uma estrat\u00e9gia de aquisi\u00e7\u00e3o direcionada que seja bem aceita pelos investidores institucionais.<\/li>\n<li><strong>Mitigar o risco:<\/strong> Aborde estrategicamente o risco de resgate, o exame minucioso da avalia\u00e7\u00e3o e os desafios cont\u00ednuos de conformidade.<\/li>\n<li><strong>Acelere o De-SPAC:<\/strong> Aproveite nossa experi\u00eancia em fus\u00f5es e aquisi\u00e7\u00f5es para garantir uma transi\u00e7\u00e3o perfeita para uma empresa de capital aberto totalmente operacional.<\/li>\n<\/ul>\n<p><strong>Agende sua consulta estrat\u00e9gica<\/strong> Entre em contato com a EQUIPE SPAC da Mergerscorp<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O lan\u00e7amento de uma Special Purpose Acquisition Company (SPAC) na Nasdaq Stock Market \u00e9 um processo de v\u00e1rias etapas que oferece um caminho mais r\u00e1pido para os mercados p\u00fablicos em compara\u00e7\u00e3o com uma Oferta P\u00fablica Inicial (IPO) tradicional. Uma SPAC \u00e9 essencialmente uma empresa de fachada com &#8220;cheque em branco&#8221; criada exclusivamente para levantar capital [&hellip;]<\/p>\n","protected":false},"author":823,"featured_media":19983,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[742],"tags":[],"class_list":{"0":"post-20879","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-editorial-pt-br"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.2 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Guia completo para o lan\u00e7amento de um SPAC na NASDAQ: da forma\u00e7\u00e3o ao encerramento do SPAC | MergersCorp M&amp;A International<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.mergerscorp.com\/pt-br\/guia-completo-para-o-lancamento-de-um-spac-na-nasdaq-da-formacao-ao-encerramento-do-spac\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Guia completo para o lan\u00e7amento de um SPAC na NASDAQ: da forma\u00e7\u00e3o ao encerramento do SPAC\" \/>\n<meta property=\"og:description\" content=\"O lan\u00e7amento de uma Special Purpose Acquisition Company (SPAC) na Nasdaq Stock Market \u00e9 um processo de v\u00e1rias etapas que oferece um caminho mais r\u00e1pido para os mercados p\u00fablicos em compara\u00e7\u00e3o com uma Oferta P\u00fablica Inicial (IPO) tradicional. Uma SPAC \u00e9 essencialmente uma empresa de fachada com &#8220;cheque em branco&#8221; criada exclusivamente para levantar capital [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.mergerscorp.com\/pt-br\/guia-completo-para-o-lancamento-de-um-spac-na-nasdaq-da-formacao-ao-encerramento-do-spac\/\" \/>\n<meta property=\"og:site_name\" content=\"MergersCorp M&amp;A International | Investment Banking\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-23T14:52:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-02T17:25:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.mergerscorp.com\/wp-content\/uploads\/2025\/11\/wall-street-sign-post-with-american-national-flags-background-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editorial Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editorial Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.mergerscorp.com\\\/pt-br\\\/guia-completo-para-o-lancamento-de-um-spac-na-nasdaq-da-formacao-ao-encerramento-do-spac\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.mergerscorp.com\\\/pt-br\\\/guia-completo-para-o-lancamento-de-um-spac-na-nasdaq-da-formacao-ao-encerramento-do-spac\\\/\"},\"author\":{\"name\":\"Editorial Team\",\"@id\":\"https:\\\/\\\/blog.mergerscorp.com\\\/#\\\/schema\\\/person\\\/bf460487ca6224809bcf72d32eefacd8\"},\"headline\":\"Guia completo para o lan\u00e7amento de um SPAC na NASDAQ: da forma\u00e7\u00e3o ao encerramento do SPAC\",\"datePublished\":\"2025-11-23T14:52:40+00:00\",\"dateModified\":\"2026-05-02T17:25:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.mergerscorp.com\\\/pt-br\\\/guia-completo-para-o-lancamento-de-um-spac-na-nasdaq-da-formacao-ao-encerramento-do-spac\\\/\"},\"wordCount\":2205,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.mergerscorp.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.mergerscorp.com\\\/pt-br\\\/guia-completo-para-o-lancamento-de-um-spac-na-nasdaq-da-formacao-ao-encerramento-do-spac\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.mergerscorp.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/wall-street-sign-post-with-american-national-flags-background-scaled.jpg\",\"articleSection\":[\"Editorial\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.mergerscorp.com\\\/pt-br\\\/guia-completo-para-o-lancamento-de-um-spac-na-nasdaq-da-formacao-ao-encerramento-do-spac\\\/\",\"url\":\"https:\\\/\\\/blog.mergerscorp.com\\\/pt-br\\\/guia-completo-para-o-lancamento-de-um-spac-na-nasdaq-da-formacao-ao-encerramento-do-spac\\\/\",\"name\":\"Guia completo para o lan\u00e7amento de um SPAC na NASDAQ: da forma\u00e7\u00e3o ao encerramento do SPAC | MergersCorp M&A International\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.mergerscorp.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.mergerscorp.com\\\/pt-br\\\/guia-completo-para-o-lancamento-de-um-spac-na-nasdaq-da-formacao-ao-encerramento-do-spac\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.mergerscorp.com\\\/pt-br\\\/guia-completo-para-o-lancamento-de-um-spac-na-nasdaq-da-formacao-ao-encerramento-do-spac\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.mergerscorp.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/wall-street-sign-post-with-american-national-flags-background-scaled.jpg\",\"datePublished\":\"2025-11-23T14:52:40+00:00\",\"dateModified\":\"2026-05-02T17:25:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.mergerscorp.com\\\/pt-br\\\/guia-completo-para-o-lancamento-de-um-spac-na-nasdaq-da-formacao-ao-encerramento-do-spac\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.mergerscorp.com\\\/pt-br\\\/guia-completo-para-o-lancamento-de-um-spac-na-nasdaq-da-formacao-ao-encerramento-do-spac\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/blog.mergerscorp.com\\\/pt-br\\\/guia-completo-para-o-lancamento-de-um-spac-na-nasdaq-da-formacao-ao-encerramento-do-spac\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.mergerscorp.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/wall-street-sign-post-with-american-national-flags-background-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.mergerscorp.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/wall-street-sign-post-with-american-national-flags-background-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"Wall Street sign post with American national flags in background. New York city financial economy district, stock market trade and exchange, or international business concept\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.mergerscorp.com\\\/pt-br\\\/guia-completo-para-o-lancamento-de-um-spac-na-nasdaq-da-formacao-ao-encerramento-do-spac\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.mergerscorp.com\\\/pt-br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Guia completo para o lan\u00e7amento de um SPAC na NASDAQ: da forma\u00e7\u00e3o ao encerramento do SPAC\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.mergerscorp.com\\\/#website\",\"url\":\"https:\\\/\\\/blog.mergerscorp.com\\\/\",\"name\":\"Mergerscorp M&A International Blog\",\"description\":\"Corporate Blog\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.mergerscorp.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.mergerscorp.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.mergerscorp.com\\\/#organization\",\"name\":\"MergersCorp M&A International\",\"url\":\"https:\\\/\\\/blog.mergerscorp.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/blog.mergerscorp.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.mergerscorp.com\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/MergersCorp-Logo-copy-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.mergerscorp.com\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/MergersCorp-Logo-copy-scaled.jpg\",\"width\":2560,\"height\":2560,\"caption\":\"MergersCorp M&A International\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.mergerscorp.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.mergerscorp.com\\\/#\\\/schema\\\/person\\\/bf460487ca6224809bcf72d32eefacd8\",\"name\":\"Editorial Team\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/blog.mergerscorp.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/MC-v3--96x96.jpg\",\"url\":\"https:\\\/\\\/blog.mergerscorp.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/MC-v3--96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.mergerscorp.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/MC-v3--96x96.jpg\",\"caption\":\"Editorial Team\"},\"description\":\"MergersCorp\u2122 is a distinguished advisory firm specializing in Investment Banking, cross-border Mergers and Acquisitions (M&amp;A) and comprehensive corporate finance solutions for clients globally.\",\"url\":\"https:\\\/\\\/blog.mergerscorp.com\\\/pt-br\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Guia completo para o lan\u00e7amento de um SPAC na NASDAQ: da forma\u00e7\u00e3o ao encerramento do SPAC | MergersCorp M&A International","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.mergerscorp.com\/pt-br\/guia-completo-para-o-lancamento-de-um-spac-na-nasdaq-da-formacao-ao-encerramento-do-spac\/","og_locale":"pt_BR","og_type":"article","og_title":"Guia completo para o lan\u00e7amento de um SPAC na NASDAQ: da forma\u00e7\u00e3o ao encerramento do SPAC","og_description":"O lan\u00e7amento de uma Special Purpose Acquisition Company (SPAC) na Nasdaq Stock Market \u00e9 um processo de v\u00e1rias etapas que oferece um caminho mais r\u00e1pido para os mercados p\u00fablicos em compara\u00e7\u00e3o com uma Oferta P\u00fablica Inicial (IPO) tradicional. Uma SPAC \u00e9 essencialmente uma empresa de fachada com &#8220;cheque em branco&#8221; criada exclusivamente para levantar capital [&hellip;]","og_url":"https:\/\/blog.mergerscorp.com\/pt-br\/guia-completo-para-o-lancamento-de-um-spac-na-nasdaq-da-formacao-ao-encerramento-do-spac\/","og_site_name":"MergersCorp M&amp;A International | Investment Banking","article_published_time":"2025-11-23T14:52:40+00:00","article_modified_time":"2026-05-02T17:25:35+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/blog.mergerscorp.com\/wp-content\/uploads\/2025\/11\/wall-street-sign-post-with-american-national-flags-background-scaled.jpg","type":"image\/jpeg"}],"author":"Editorial Team","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Editorial Team","Est. tempo de leitura":"11 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.mergerscorp.com\/pt-br\/guia-completo-para-o-lancamento-de-um-spac-na-nasdaq-da-formacao-ao-encerramento-do-spac\/#article","isPartOf":{"@id":"https:\/\/blog.mergerscorp.com\/pt-br\/guia-completo-para-o-lancamento-de-um-spac-na-nasdaq-da-formacao-ao-encerramento-do-spac\/"},"author":{"name":"Editorial Team","@id":"https:\/\/blog.mergerscorp.com\/#\/schema\/person\/bf460487ca6224809bcf72d32eefacd8"},"headline":"Guia completo para o lan\u00e7amento de um SPAC na NASDAQ: da forma\u00e7\u00e3o ao encerramento do SPAC","datePublished":"2025-11-23T14:52:40+00:00","dateModified":"2026-05-02T17:25:35+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.mergerscorp.com\/pt-br\/guia-completo-para-o-lancamento-de-um-spac-na-nasdaq-da-formacao-ao-encerramento-do-spac\/"},"wordCount":2205,"publisher":{"@id":"https:\/\/blog.mergerscorp.com\/#organization"},"image":{"@id":"https:\/\/blog.mergerscorp.com\/pt-br\/guia-completo-para-o-lancamento-de-um-spac-na-nasdaq-da-formacao-ao-encerramento-do-spac\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.mergerscorp.com\/wp-content\/uploads\/2025\/11\/wall-street-sign-post-with-american-national-flags-background-scaled.jpg","articleSection":["Editorial"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/blog.mergerscorp.com\/pt-br\/guia-completo-para-o-lancamento-de-um-spac-na-nasdaq-da-formacao-ao-encerramento-do-spac\/","url":"https:\/\/blog.mergerscorp.com\/pt-br\/guia-completo-para-o-lancamento-de-um-spac-na-nasdaq-da-formacao-ao-encerramento-do-spac\/","name":"Guia completo para o lan\u00e7amento de um SPAC na NASDAQ: da forma\u00e7\u00e3o ao encerramento do SPAC | MergersCorp M&A International","isPartOf":{"@id":"https:\/\/blog.mergerscorp.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.mergerscorp.com\/pt-br\/guia-completo-para-o-lancamento-de-um-spac-na-nasdaq-da-formacao-ao-encerramento-do-spac\/#primaryimage"},"image":{"@id":"https:\/\/blog.mergerscorp.com\/pt-br\/guia-completo-para-o-lancamento-de-um-spac-na-nasdaq-da-formacao-ao-encerramento-do-spac\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.mergerscorp.com\/wp-content\/uploads\/2025\/11\/wall-street-sign-post-with-american-national-flags-background-scaled.jpg","datePublished":"2025-11-23T14:52:40+00:00","dateModified":"2026-05-02T17:25:35+00:00","breadcrumb":{"@id":"https:\/\/blog.mergerscorp.com\/pt-br\/guia-completo-para-o-lancamento-de-um-spac-na-nasdaq-da-formacao-ao-encerramento-do-spac\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.mergerscorp.com\/pt-br\/guia-completo-para-o-lancamento-de-um-spac-na-nasdaq-da-formacao-ao-encerramento-do-spac\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/blog.mergerscorp.com\/pt-br\/guia-completo-para-o-lancamento-de-um-spac-na-nasdaq-da-formacao-ao-encerramento-do-spac\/#primaryimage","url":"https:\/\/blog.mergerscorp.com\/wp-content\/uploads\/2025\/11\/wall-street-sign-post-with-american-national-flags-background-scaled.jpg","contentUrl":"https:\/\/blog.mergerscorp.com\/wp-content\/uploads\/2025\/11\/wall-street-sign-post-with-american-national-flags-background-scaled.jpg","width":2560,"height":1707,"caption":"Wall Street sign post with American national flags in background. New York city financial economy district, stock market trade and exchange, or international business concept"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.mergerscorp.com\/pt-br\/guia-completo-para-o-lancamento-de-um-spac-na-nasdaq-da-formacao-ao-encerramento-do-spac\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.mergerscorp.com\/pt-br\/"},{"@type":"ListItem","position":2,"name":"Guia completo para o lan\u00e7amento de um SPAC na NASDAQ: da forma\u00e7\u00e3o ao encerramento do SPAC"}]},{"@type":"WebSite","@id":"https:\/\/blog.mergerscorp.com\/#website","url":"https:\/\/blog.mergerscorp.com\/","name":"Mergerscorp M&A International Blog","description":"Corporate Blog","publisher":{"@id":"https:\/\/blog.mergerscorp.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.mergerscorp.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/blog.mergerscorp.com\/#organization","name":"MergersCorp M&A International","url":"https:\/\/blog.mergerscorp.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/blog.mergerscorp.com\/#\/schema\/logo\/image\/","url":"https:\/\/blog.mergerscorp.com\/wp-content\/uploads\/2021\/08\/MergersCorp-Logo-copy-scaled.jpg","contentUrl":"https:\/\/blog.mergerscorp.com\/wp-content\/uploads\/2021\/08\/MergersCorp-Logo-copy-scaled.jpg","width":2560,"height":2560,"caption":"MergersCorp M&A International"},"image":{"@id":"https:\/\/blog.mergerscorp.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/blog.mergerscorp.com\/#\/schema\/person\/bf460487ca6224809bcf72d32eefacd8","name":"Editorial Team","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/blog.mergerscorp.com\/wp-content\/uploads\/2026\/04\/MC-v3--96x96.jpg","url":"https:\/\/blog.mergerscorp.com\/wp-content\/uploads\/2026\/04\/MC-v3--96x96.jpg","contentUrl":"https:\/\/blog.mergerscorp.com\/wp-content\/uploads\/2026\/04\/MC-v3--96x96.jpg","caption":"Editorial Team"},"description":"MergersCorp\u2122 is a distinguished advisory firm specializing in Investment Banking, cross-border Mergers and Acquisitions (M&amp;A) and comprehensive corporate finance solutions for clients globally.","url":"https:\/\/blog.mergerscorp.com\/pt-br\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.mergerscorp.com\/pt-br\/wp-json\/wp\/v2\/posts\/20879","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.mergerscorp.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.mergerscorp.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.mergerscorp.com\/pt-br\/wp-json\/wp\/v2\/users\/823"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.mergerscorp.com\/pt-br\/wp-json\/wp\/v2\/comments?post=20879"}],"version-history":[{"count":1,"href":"https:\/\/blog.mergerscorp.com\/pt-br\/wp-json\/wp\/v2\/posts\/20879\/revisions"}],"predecessor-version":[{"id":23315,"href":"https:\/\/blog.mergerscorp.com\/pt-br\/wp-json\/wp\/v2\/posts\/20879\/revisions\/23315"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.mergerscorp.com\/pt-br\/wp-json\/wp\/v2\/media\/19983"}],"wp:attachment":[{"href":"https:\/\/blog.mergerscorp.com\/pt-br\/wp-json\/wp\/v2\/media?parent=20879"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.mergerscorp.com\/pt-br\/wp-json\/wp\/v2\/categories?post=20879"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.mergerscorp.com\/pt-br\/wp-json\/wp\/v2\/tags?post=20879"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}