{"id":20901,"date":"2025-12-22T21:04:18","date_gmt":"2025-12-22T21:04:18","guid":{"rendered":"https:\/\/blog.mergerscorp.com\/1point1-solutions-nse-onepointone-anuncia-a-aquisicao-por-3337-milhoes-de-dolares-da-netcom-lider-em-bpo-na-america-central\/"},"modified":"2026-05-02T17:25:33","modified_gmt":"2026-05-02T17:25:33","slug":"1point1-solutions-nse-onepointone-anuncia-a-aquisicao-por-3337-milhoes-de-dolares-da-netcom-lider-em-bpo-na-america-central","status":"publish","type":"post","link":"https:\/\/blog.mergerscorp.com\/pt-br\/1point1-solutions-nse-onepointone-anuncia-a-aquisicao-por-3337-milhoes-de-dolares-da-netcom-lider-em-bpo-na-america-central\/","title":{"rendered":"1Point1 Solutions (NSE: ONEPOINTONE) anuncia a aquisi\u00e7\u00e3o, por 33,37 milh\u00f5es de d\u00f3lares, da Netcom, l\u00edder em BPO na Am\u00e9rica Central"},"content":{"rendered":"<p data-path-to-node=\"2\"><b data-path-to-node=\"2\" data-index-in-node=\"0\">MUMBAI, \u00cdNDIA \/ SAN JOSE, COSTA RICA &#8211; 22 de dezembro de 2025<\/b> &#8211; A 1Point1 Solutions Ltd. (NSE: ONEPOINTONE \/ BSE: 543886), fornecedora l\u00edder de servi\u00e7os de transforma\u00e7\u00e3o digital e gerenciamento de processos de neg\u00f3cios (BPM) orientados por IA, anunciou hoje que celebrou um contrato definitivo de compra de a\u00e7\u00f5es (SPA) para adquirir 100% da propriedade da <b data-path-to-node=\"2\" data-index-in-node=\"333\">Netcom Business Communication Center (&#8220;Netcom&#8221;)<\/b>, uma proeminente operadora de BPO nearshore e contact center com sede na Costa Rica.<\/p>\n<p data-path-to-node=\"3\">O valor total da transa\u00e7\u00e3o para a aquisi\u00e7\u00e3o \u00e9 de <b data-path-to-node=\"3\" data-index-in-node=\"51\">US$ 33,37 milh\u00f5es<\/b>, compreendendo um pagamento adiantado de US$ 25,41 milh\u00f5es e um ganho estimado de US$ 8,25 milh\u00f5es, sujeito a ajustes p\u00f3s-fechamento vinculados ao desempenho do EBITDA e ao excesso de capital de giro. A aquisi\u00e7\u00e3o est\u00e1 prevista para ser conclu\u00edda at\u00e9 31 de mar\u00e7o de 2026. <\/p>\n<p data-path-to-node=\"3\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-20051\" src=\"https:\/\/blog.mergerscorp.com\/wp-content\/uploads\/2025\/12\/Stone.jpg\" alt=\"\" width=\"736\" height=\"1096\" srcset=\"https:\/\/blog.mergerscorp.com\/wp-content\/uploads\/2025\/12\/Stone.jpg 736w, https:\/\/blog.mergerscorp.com\/wp-content\/uploads\/2025\/12\/Stone-201x300.jpg 201w, https:\/\/blog.mergerscorp.com\/wp-content\/uploads\/2025\/12\/Stone-688x1024.jpg 688w, https:\/\/blog.mergerscorp.com\/wp-content\/uploads\/2025\/12\/Stone-150x223.jpg 150w, https:\/\/blog.mergerscorp.com\/wp-content\/uploads\/2025\/12\/Stone-300x447.jpg 300w, https:\/\/blog.mergerscorp.com\/wp-content\/uploads\/2025\/12\/Stone-696x1036.jpg 696w\" sizes=\"auto, (max-width: 736px) 100vw, 736px\" \/><\/p>\n<h3 data-path-to-node=\"4\">Entrada estrat\u00e9gica na Am\u00e9rica Latina<\/h3>\n<p data-path-to-node=\"5\">Essa aquisi\u00e7\u00e3o hist\u00f3rica marca a entrada decisiva da 1Point1 no mercado cr\u00edtico da Am\u00e9rica Latina (LATAM). Ao integrar a robusta infraestrutura de entrega da Netcom na <b data-path-to-node=\"5\" data-index-in-node=\"168\">Costa Rica, Panam\u00e1, Col\u00f4mbia e M\u00e9xico<\/b>, a 1Point1 estabelece imediatamente uma presen\u00e7a nearshore bil\u00edngue (ingl\u00eas\/espanhol) de alta qualidade. Essa mudan\u00e7a atende \u00e0 crescente demanda de clientes internacionais por servi\u00e7os que ofere\u00e7am afinidade cultural, alinhamento de fuso hor\u00e1rio e maior resili\u00eancia operacional.  <\/p>\n<p data-path-to-node=\"6\">A transa\u00e7\u00e3o foi orquestrada com sucesso com a consultoria financeira e estrat\u00e9gica da <b data-path-to-node=\"6\" data-index-in-node=\"89\">MergersCorp<\/b>, uma empresa americana de consultoria em bancos de investimento e fus\u00f5es e aquisi\u00e7\u00f5es internacionais reconhecida mundialmente, com a total coopera\u00e7\u00e3o do vendedor da Netcom, Fernando Murillo Porras.<\/p>\n<h3 data-path-to-node=\"7\">Sinergia financeira e operacional<\/h3>\n<p data-path-to-node=\"8\">Espera-se que a aquisi\u00e7\u00e3o <b data-path-to-node=\"8\" data-index-in-node=\"31\">quase dobre a receita da 1Point1 no ano fiscal de 27<\/b>, marcando uma etapa significativa na estrat\u00e9gia de crescimento inorg\u00e2nico da empresa.<\/p>\n<ul data-path-to-node=\"9\">\n<li>\n<p data-path-to-node=\"9,0,0\"><b data-path-to-node=\"9,0,0\" data-index-in-node=\"0\">Escala global:<\/b> A adi\u00e7\u00e3o dos mais de 500 profissionais da Netcom \u00e0 for\u00e7a de trabalho existente da 1Point1, de mais de 6.000, cria uma entidade global combinada de mais de <b data-path-to-node=\"9,0,0\" data-index-in-node=\"141\">6.500 profissionais<\/b>.<\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"9,1,0\"><b data-path-to-node=\"9,1,0\" data-index-in-node=\"0\">Expans\u00e3o do setor:<\/b> O acordo amplia os recursos de CX e BPM da 1Point1, que priorizam a IA, para o ecossistema de <b data-path-to-node=\"9,1,0\" data-index-in-node=\"94\">servi\u00e7os banc\u00e1rios e financeiros (BFSI)<\/b> nas Am\u00e9ricas do Norte, Central e Latina.<\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"9,2,0\"><b data-path-to-node=\"9,2,0\" data-index-in-node=\"0\">Rentabilidade:<\/b> a 1Point1 espera manter as margens do EBITDA na faixa de <b data-path-to-node=\"9,2,0\" data-index-in-node=\"74\">25 a 30%<\/b>, mesmo enquanto continua investindo em tecnologia, talentos e futuras aquisi\u00e7\u00f5es.<\/p>\n<\/li>\n<\/ul>\n<h3 data-path-to-node=\"10\">Perspectivas de lideran\u00e7a<\/h3>\n<figure id=\"attachment_20039\" aria-describedby=\"caption-attachment-20039\" style=\"width: 800px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-20039 size-full\" src=\"https:\/\/blog.mergerscorp.com\/wp-content\/uploads\/2025\/12\/1731582699583.jpeg\" alt=\"\" width=\"800\" height=\"800\" srcset=\"https:\/\/blog.mergerscorp.com\/wp-content\/uploads\/2025\/12\/1731582699583.jpeg 800w, https:\/\/blog.mergerscorp.com\/wp-content\/uploads\/2025\/12\/1731582699583-300x300.jpeg 300w, https:\/\/blog.mergerscorp.com\/wp-content\/uploads\/2025\/12\/1731582699583-150x150.jpeg 150w, https:\/\/blog.mergerscorp.com\/wp-content\/uploads\/2025\/12\/1731582699583-768x768.jpeg 768w, https:\/\/blog.mergerscorp.com\/wp-content\/uploads\/2025\/12\/1731582699583-696x696.jpeg 696w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption id=\"caption-attachment-20039\" class=\"wp-caption-text\">Akshay Chhabra, presidente e diretor administrativo da 1Point1 Solutions Ltd.<\/figcaption><\/figure>\n<p data-path-to-node=\"11\"><b data-path-to-node=\"11\" data-index-in-node=\"0\">Akshay Chhabra, presidente e diretor administrativo da 1Point1 Solutions Ltd. comentou:<\/b><\/p>\n<p data-path-to-node=\"12,0\"><em>&#8220;Este \u00e9 um momento de transforma\u00e7\u00e3o para a 1Point1. A aquisi\u00e7\u00e3o da Netcom fortalece nossa presen\u00e7a nas Am\u00e9ricas do Norte, Central e Latina e expande nossa presen\u00e7a BFSI em todos os continentes. Essa mudan\u00e7a atende diretamente \u00e0 crescente demanda por servi\u00e7os de BPO nearshore e fornece a plataforma de lan\u00e7amento perfeita para acelerar nossa estrat\u00e9gia de crescimento global e incorporar nossa automa\u00e7\u00e3o liderada pela GenAI em toda a regi\u00e3o da Am\u00e9rica Latina.&#8221;<\/em><\/p>\n<p data-path-to-node=\"13\"><b data-path-to-node=\"13\" data-index-in-node=\"0\">A equipe da MergersCorp, liderada por Edward Sklar (COO), Stefano Endrizzi (s\u00f3cio s\u00eanior), Fernando Salvaterra (associado) e Dharmesh Rathod (associado), declarou:<\/b><\/p>\n<p data-path-to-node=\"14,0\"><em>&#8220;Estamos orgulhosos de ter facilitado esse neg\u00f3cio transfronteiri\u00e7o hist\u00f3rico. O alinhamento estrat\u00e9gico entre a experi\u00eancia em transforma\u00e7\u00e3o digital da 1Point1 e as opera\u00e7\u00f5es nearshore estabelecidas da Netcom \u00e9 excepcional. Essa transa\u00e7\u00e3o cria valor imediato e estabelece uma entidade poderosa e globalmente competitiva no cen\u00e1rio de BPM.&#8221;<\/em><\/p>\n<h3 data-path-to-node=\"15\">Tecnologia e continuidade<\/h3>\n<p data-path-to-node=\"16\">A entidade rec\u00e9m-integrada aproveitar\u00e1 a tecnologia propriet\u00e1ria da 1Point1 e <b data-path-to-node=\"16\" data-index-in-node=\"79\">as plataformas habilitadas para GenAI<\/b> para aprimorar as opera\u00e7\u00f5es da Netcom, com foco em resultados superiores para o cliente, maior efici\u00eancia e inova\u00e7\u00e3o de servi\u00e7os. Todas as equipes operacionais e de lideran\u00e7a existentes da Netcom ser\u00e3o mantidas para garantir a continuidade perfeita para clientes e funcion\u00e1rios. <\/p>\n<h3 data-path-to-node=\"18\">Sobre a 1Point1 Solutions Ltd.<\/h3>\n<p data-path-to-node=\"19\">Fundada em 2008 e sediada em Navi Mumbai, \u00cdndia, a 1Point1 Solutions (NSE: ONEPOINTONE \/ BSE: 543886) \u00e9 uma fornecedora de capital aberto de servi\u00e7os de transforma\u00e7\u00e3o digital e BPM com IA. Com mais de 6.000 profissionais e nove centros de entrega globais, a empresa oferece um conjunto de servi\u00e7os que inclui gerenciamento de CX, transforma\u00e7\u00e3o digital, finan\u00e7as e contabilidade e confian\u00e7a e seguran\u00e7a nos EUA, Europa e \u00c1sia.<\/p>\n<h3 data-path-to-node=\"20\">Sobre o Netcom Business Communication Center<\/h3>\n<p data-path-to-node=\"21\">A Netcom \u00e9 uma operadora l\u00edder de BPO nearshore com opera\u00e7\u00f5es na Costa Rica, Panam\u00e1, Col\u00f4mbia e M\u00e9xico. \u00c9 especializada no fornecimento de atendimento ao cliente bil\u00edngue de alta qualidade, suporte t\u00e9cnico e telesservi\u00e7os, aproveitando sua localiza\u00e7\u00e3o geogr\u00e1fica estrat\u00e9gica para atender ao mercado norte-americano. <\/p>\n<h3 data-path-to-node=\"22\">Sobre a MergersCorp<\/h3>\n<p data-path-to-node=\"23\">A MergersCorp \u00e9 uma empresa americana de consultoria em bancos de investimento e fus\u00f5es e aquisi\u00e7\u00f5es internacionais reconhecida mundialmente, especializada no mercado m\u00e9dio-baixo e m\u00e9dio. Ela fornece orienta\u00e7\u00e3o especializada e solu\u00e7\u00f5es de finan\u00e7as corporativas para clientes em todo o mundo, facilitando fus\u00f5es e aquisi\u00e7\u00f5es estrat\u00e9gicas em v\u00e1rios setores. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>MUMBAI, \u00cdNDIA \/ SAN JOSE, COSTA RICA &#8211; 22 de dezembro de 2025 &#8211; A 1Point1 Solutions Ltd. (NSE: ONEPOINTONE \/ BSE: 543886), fornecedora l\u00edder de servi\u00e7os de transforma\u00e7\u00e3o digital e gerenciamento de processos de neg\u00f3cios (BPM) orientados por IA, anunciou hoje que celebrou um contrato definitivo de compra de a\u00e7\u00f5es (SPA) para adquirir 100% [&hellip;]<\/p>\n","protected":false},"author":823,"featured_media":20035,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[691],"tags":[],"class_list":{"0":"post-20901","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-noticias"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.2 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>1Point1 Solutions (NSE: ONEPOINTONE) anuncia a aquisi\u00e7\u00e3o, por 33,37 milh\u00f5es de d\u00f3lares, da Netcom, l\u00edder em BPO na Am\u00e9rica Central | MergersCorp M&amp;A International<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.mergerscorp.com\/pt-br\/1point1-solutions-nse-onepointone-anuncia-a-aquisicao-por-3337-milhoes-de-dolares-da-netcom-lider-em-bpo-na-america-central\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"1Point1 Solutions (NSE: ONEPOINTONE) anuncia a aquisi\u00e7\u00e3o, por 33,37 milh\u00f5es de d\u00f3lares, da Netcom, l\u00edder em BPO na Am\u00e9rica Central\" \/>\n<meta property=\"og:description\" content=\"MUMBAI, \u00cdNDIA \/ SAN JOSE, COSTA RICA &#8211; 22 de dezembro de 2025 &#8211; A 1Point1 Solutions Ltd. (NSE: ONEPOINTONE \/ BSE: 543886), fornecedora l\u00edder de servi\u00e7os de transforma\u00e7\u00e3o digital e gerenciamento de processos de neg\u00f3cios (BPM) orientados por IA, anunciou hoje que celebrou um contrato definitivo de compra de a\u00e7\u00f5es (SPA) para adquirir 100% [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.mergerscorp.com\/pt-br\/1point1-solutions-nse-onepointone-anuncia-a-aquisicao-por-3337-milhoes-de-dolares-da-netcom-lider-em-bpo-na-america-central\/\" \/>\n<meta property=\"og:site_name\" content=\"MergersCorp M&amp;A International | Investment Banking\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-22T21:04:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-02T17:25:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.mergerscorp.com\/wp-content\/uploads\/2025\/12\/2399149.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1125\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editorial Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editorial Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.mergerscorp.com\\\/pt-br\\\/1point1-solutions-nse-onepointone-anuncia-a-aquisicao-por-3337-milhoes-de-dolares-da-netcom-lider-em-bpo-na-america-central\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.mergerscorp.com\\\/pt-br\\\/1point1-solutions-nse-onepointone-anuncia-a-aquisicao-por-3337-milhoes-de-dolares-da-netcom-lider-em-bpo-na-america-central\\\/\"},\"author\":{\"name\":\"Editorial Team\",\"@id\":\"https:\\\/\\\/blog.mergerscorp.com\\\/#\\\/schema\\\/person\\\/bf460487ca6224809bcf72d32eefacd8\"},\"headline\":\"1Point1 Solutions (NSE: ONEPOINTONE) anuncia a aquisi\u00e7\u00e3o, por 33,37 milh\u00f5es de d\u00f3lares, da Netcom, l\u00edder em BPO na Am\u00e9rica Central\",\"datePublished\":\"2025-12-22T21:04:18+00:00\",\"dateModified\":\"2026-05-02T17:25:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.mergerscorp.com\\\/pt-br\\\/1point1-solutions-nse-onepointone-anuncia-a-aquisicao-por-3337-milhoes-de-dolares-da-netcom-lider-em-bpo-na-america-central\\\/\"},\"wordCount\":873,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.mergerscorp.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.mergerscorp.com\\\/pt-br\\\/1point1-solutions-nse-onepointone-anuncia-a-aquisicao-por-3337-milhoes-de-dolares-da-netcom-lider-em-bpo-na-america-central\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.mergerscorp.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/2399149.jpg\",\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.mergerscorp.com\\\/pt-br\\\/1point1-solutions-nse-onepointone-anuncia-a-aquisicao-por-3337-milhoes-de-dolares-da-netcom-lider-em-bpo-na-america-central\\\/\",\"url\":\"https:\\\/\\\/blog.mergerscorp.com\\\/pt-br\\\/1point1-solutions-nse-onepointone-anuncia-a-aquisicao-por-3337-milhoes-de-dolares-da-netcom-lider-em-bpo-na-america-central\\\/\",\"name\":\"1Point1 Solutions (NSE: ONEPOINTONE) anuncia a aquisi\u00e7\u00e3o, por 33,37 milh\u00f5es de d\u00f3lares, da Netcom, l\u00edder em BPO na Am\u00e9rica Central | MergersCorp M&A International\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.mergerscorp.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.mergerscorp.com\\\/pt-br\\\/1point1-solutions-nse-onepointone-anuncia-a-aquisicao-por-3337-milhoes-de-dolares-da-netcom-lider-em-bpo-na-america-central\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.mergerscorp.com\\\/pt-br\\\/1point1-solutions-nse-onepointone-anuncia-a-aquisicao-por-3337-milhoes-de-dolares-da-netcom-lider-em-bpo-na-america-central\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.mergerscorp.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/2399149.jpg\",\"datePublished\":\"2025-12-22T21:04:18+00:00\",\"dateModified\":\"2026-05-02T17:25:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.mergerscorp.com\\\/pt-br\\\/1point1-solutions-nse-onepointone-anuncia-a-aquisicao-por-3337-milhoes-de-dolares-da-netcom-lider-em-bpo-na-america-central\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.mergerscorp.com\\\/pt-br\\\/1point1-solutions-nse-onepointone-anuncia-a-aquisicao-por-3337-milhoes-de-dolares-da-netcom-lider-em-bpo-na-america-central\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/blog.mergerscorp.com\\\/pt-br\\\/1point1-solutions-nse-onepointone-anuncia-a-aquisicao-por-3337-milhoes-de-dolares-da-netcom-lider-em-bpo-na-america-central\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.mergerscorp.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/2399149.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.mergerscorp.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/2399149.jpg\",\"width\":2000,\"height\":1125},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.mergerscorp.com\\\/pt-br\\\/1point1-solutions-nse-onepointone-anuncia-a-aquisicao-por-3337-milhoes-de-dolares-da-netcom-lider-em-bpo-na-america-central\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.mergerscorp.com\\\/pt-br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"1Point1 Solutions (NSE: ONEPOINTONE) anuncia a aquisi\u00e7\u00e3o, por 33,37 milh\u00f5es de d\u00f3lares, da Netcom, l\u00edder em BPO na Am\u00e9rica Central\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.mergerscorp.com\\\/#website\",\"url\":\"https:\\\/\\\/blog.mergerscorp.com\\\/\",\"name\":\"Mergerscorp M&A International Blog\",\"description\":\"Corporate Blog\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.mergerscorp.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.mergerscorp.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.mergerscorp.com\\\/#organization\",\"name\":\"MergersCorp M&A International\",\"url\":\"https:\\\/\\\/blog.mergerscorp.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/blog.mergerscorp.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.mergerscorp.com\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/MergersCorp-Logo-copy-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.mergerscorp.com\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/MergersCorp-Logo-copy-scaled.jpg\",\"width\":2560,\"height\":2560,\"caption\":\"MergersCorp M&A International\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.mergerscorp.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.mergerscorp.com\\\/#\\\/schema\\\/person\\\/bf460487ca6224809bcf72d32eefacd8\",\"name\":\"Editorial Team\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/blog.mergerscorp.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/MC-v3--96x96.jpg\",\"url\":\"https:\\\/\\\/blog.mergerscorp.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/MC-v3--96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.mergerscorp.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/MC-v3--96x96.jpg\",\"caption\":\"Editorial Team\"},\"description\":\"MergersCorp\u2122 is a distinguished advisory firm specializing in Investment Banking, cross-border Mergers and Acquisitions (M&amp;A) and comprehensive corporate finance solutions for clients globally.\",\"url\":\"https:\\\/\\\/blog.mergerscorp.com\\\/pt-br\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"1Point1 Solutions (NSE: ONEPOINTONE) anuncia a aquisi\u00e7\u00e3o, por 33,37 milh\u00f5es de d\u00f3lares, da Netcom, l\u00edder em BPO na Am\u00e9rica Central | MergersCorp M&A International","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.mergerscorp.com\/pt-br\/1point1-solutions-nse-onepointone-anuncia-a-aquisicao-por-3337-milhoes-de-dolares-da-netcom-lider-em-bpo-na-america-central\/","og_locale":"pt_BR","og_type":"article","og_title":"1Point1 Solutions (NSE: ONEPOINTONE) anuncia a aquisi\u00e7\u00e3o, por 33,37 milh\u00f5es de d\u00f3lares, da Netcom, l\u00edder em BPO na Am\u00e9rica Central","og_description":"MUMBAI, \u00cdNDIA \/ SAN JOSE, COSTA RICA &#8211; 22 de dezembro de 2025 &#8211; A 1Point1 Solutions Ltd. (NSE: ONEPOINTONE \/ BSE: 543886), fornecedora l\u00edder de servi\u00e7os de transforma\u00e7\u00e3o digital e gerenciamento de processos de neg\u00f3cios (BPM) orientados por IA, anunciou hoje que celebrou um contrato definitivo de compra de a\u00e7\u00f5es (SPA) para adquirir 100% [&hellip;]","og_url":"https:\/\/blog.mergerscorp.com\/pt-br\/1point1-solutions-nse-onepointone-anuncia-a-aquisicao-por-3337-milhoes-de-dolares-da-netcom-lider-em-bpo-na-america-central\/","og_site_name":"MergersCorp M&amp;A International | Investment Banking","article_published_time":"2025-12-22T21:04:18+00:00","article_modified_time":"2026-05-02T17:25:33+00:00","og_image":[{"width":2000,"height":1125,"url":"https:\/\/blog.mergerscorp.com\/wp-content\/uploads\/2025\/12\/2399149.jpg","type":"image\/jpeg"}],"author":"Editorial Team","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Editorial Team","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.mergerscorp.com\/pt-br\/1point1-solutions-nse-onepointone-anuncia-a-aquisicao-por-3337-milhoes-de-dolares-da-netcom-lider-em-bpo-na-america-central\/#article","isPartOf":{"@id":"https:\/\/blog.mergerscorp.com\/pt-br\/1point1-solutions-nse-onepointone-anuncia-a-aquisicao-por-3337-milhoes-de-dolares-da-netcom-lider-em-bpo-na-america-central\/"},"author":{"name":"Editorial Team","@id":"https:\/\/blog.mergerscorp.com\/#\/schema\/person\/bf460487ca6224809bcf72d32eefacd8"},"headline":"1Point1 Solutions (NSE: ONEPOINTONE) anuncia a aquisi\u00e7\u00e3o, por 33,37 milh\u00f5es de d\u00f3lares, da Netcom, l\u00edder em BPO na Am\u00e9rica Central","datePublished":"2025-12-22T21:04:18+00:00","dateModified":"2026-05-02T17:25:33+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.mergerscorp.com\/pt-br\/1point1-solutions-nse-onepointone-anuncia-a-aquisicao-por-3337-milhoes-de-dolares-da-netcom-lider-em-bpo-na-america-central\/"},"wordCount":873,"publisher":{"@id":"https:\/\/blog.mergerscorp.com\/#organization"},"image":{"@id":"https:\/\/blog.mergerscorp.com\/pt-br\/1point1-solutions-nse-onepointone-anuncia-a-aquisicao-por-3337-milhoes-de-dolares-da-netcom-lider-em-bpo-na-america-central\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.mergerscorp.com\/wp-content\/uploads\/2025\/12\/2399149.jpg","articleSection":["Not\u00edcias"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/blog.mergerscorp.com\/pt-br\/1point1-solutions-nse-onepointone-anuncia-a-aquisicao-por-3337-milhoes-de-dolares-da-netcom-lider-em-bpo-na-america-central\/","url":"https:\/\/blog.mergerscorp.com\/pt-br\/1point1-solutions-nse-onepointone-anuncia-a-aquisicao-por-3337-milhoes-de-dolares-da-netcom-lider-em-bpo-na-america-central\/","name":"1Point1 Solutions (NSE: ONEPOINTONE) anuncia a aquisi\u00e7\u00e3o, por 33,37 milh\u00f5es de d\u00f3lares, da Netcom, l\u00edder em BPO na Am\u00e9rica Central | MergersCorp M&A International","isPartOf":{"@id":"https:\/\/blog.mergerscorp.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.mergerscorp.com\/pt-br\/1point1-solutions-nse-onepointone-anuncia-a-aquisicao-por-3337-milhoes-de-dolares-da-netcom-lider-em-bpo-na-america-central\/#primaryimage"},"image":{"@id":"https:\/\/blog.mergerscorp.com\/pt-br\/1point1-solutions-nse-onepointone-anuncia-a-aquisicao-por-3337-milhoes-de-dolares-da-netcom-lider-em-bpo-na-america-central\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.mergerscorp.com\/wp-content\/uploads\/2025\/12\/2399149.jpg","datePublished":"2025-12-22T21:04:18+00:00","dateModified":"2026-05-02T17:25:33+00:00","breadcrumb":{"@id":"https:\/\/blog.mergerscorp.com\/pt-br\/1point1-solutions-nse-onepointone-anuncia-a-aquisicao-por-3337-milhoes-de-dolares-da-netcom-lider-em-bpo-na-america-central\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.mergerscorp.com\/pt-br\/1point1-solutions-nse-onepointone-anuncia-a-aquisicao-por-3337-milhoes-de-dolares-da-netcom-lider-em-bpo-na-america-central\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/blog.mergerscorp.com\/pt-br\/1point1-solutions-nse-onepointone-anuncia-a-aquisicao-por-3337-milhoes-de-dolares-da-netcom-lider-em-bpo-na-america-central\/#primaryimage","url":"https:\/\/blog.mergerscorp.com\/wp-content\/uploads\/2025\/12\/2399149.jpg","contentUrl":"https:\/\/blog.mergerscorp.com\/wp-content\/uploads\/2025\/12\/2399149.jpg","width":2000,"height":1125},{"@type":"BreadcrumbList","@id":"https:\/\/blog.mergerscorp.com\/pt-br\/1point1-solutions-nse-onepointone-anuncia-a-aquisicao-por-3337-milhoes-de-dolares-da-netcom-lider-em-bpo-na-america-central\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.mergerscorp.com\/pt-br\/"},{"@type":"ListItem","position":2,"name":"1Point1 Solutions (NSE: ONEPOINTONE) anuncia a aquisi\u00e7\u00e3o, por 33,37 milh\u00f5es de d\u00f3lares, da Netcom, l\u00edder em BPO na Am\u00e9rica Central"}]},{"@type":"WebSite","@id":"https:\/\/blog.mergerscorp.com\/#website","url":"https:\/\/blog.mergerscorp.com\/","name":"Mergerscorp M&A International Blog","description":"Corporate Blog","publisher":{"@id":"https:\/\/blog.mergerscorp.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.mergerscorp.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/blog.mergerscorp.com\/#organization","name":"MergersCorp M&A International","url":"https:\/\/blog.mergerscorp.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/blog.mergerscorp.com\/#\/schema\/logo\/image\/","url":"https:\/\/blog.mergerscorp.com\/wp-content\/uploads\/2021\/08\/MergersCorp-Logo-copy-scaled.jpg","contentUrl":"https:\/\/blog.mergerscorp.com\/wp-content\/uploads\/2021\/08\/MergersCorp-Logo-copy-scaled.jpg","width":2560,"height":2560,"caption":"MergersCorp M&A International"},"image":{"@id":"https:\/\/blog.mergerscorp.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/blog.mergerscorp.com\/#\/schema\/person\/bf460487ca6224809bcf72d32eefacd8","name":"Editorial Team","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/blog.mergerscorp.com\/wp-content\/uploads\/2026\/04\/MC-v3--96x96.jpg","url":"https:\/\/blog.mergerscorp.com\/wp-content\/uploads\/2026\/04\/MC-v3--96x96.jpg","contentUrl":"https:\/\/blog.mergerscorp.com\/wp-content\/uploads\/2026\/04\/MC-v3--96x96.jpg","caption":"Editorial Team"},"description":"MergersCorp\u2122 is a distinguished advisory firm specializing in Investment Banking, cross-border Mergers and Acquisitions (M&amp;A) and comprehensive corporate finance solutions for clients globally.","url":"https:\/\/blog.mergerscorp.com\/pt-br\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.mergerscorp.com\/pt-br\/wp-json\/wp\/v2\/posts\/20901","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.mergerscorp.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.mergerscorp.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.mergerscorp.com\/pt-br\/wp-json\/wp\/v2\/users\/823"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.mergerscorp.com\/pt-br\/wp-json\/wp\/v2\/comments?post=20901"}],"version-history":[{"count":1,"href":"https:\/\/blog.mergerscorp.com\/pt-br\/wp-json\/wp\/v2\/posts\/20901\/revisions"}],"predecessor-version":[{"id":23298,"href":"https:\/\/blog.mergerscorp.com\/pt-br\/wp-json\/wp\/v2\/posts\/20901\/revisions\/23298"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.mergerscorp.com\/pt-br\/wp-json\/wp\/v2\/media\/20035"}],"wp:attachment":[{"href":"https:\/\/blog.mergerscorp.com\/pt-br\/wp-json\/wp\/v2\/media?parent=20901"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.mergerscorp.com\/pt-br\/wp-json\/wp\/v2\/categories?post=20901"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.mergerscorp.com\/pt-br\/wp-json\/wp\/v2\/tags?post=20901"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}